{"id":14952,"date":"2023-12-06T10:41:12","date_gmt":"2023-12-06T14:41:12","guid":{"rendered":"https:\/\/colegiodelapurisima.cl\/colegio-pc\/?p=14952"},"modified":"2023-12-06T10:41:12","modified_gmt":"2023-12-06T14:41:12","slug":"convivencia-escolar-te-invita-a-unas-vacaciones-libre-de-pantallas","status":"publish","type":"post","link":"https:\/\/colegiodelapurisima.cl\/colegio-pc\/convivencia-escolar-te-invita-a-unas-vacaciones-libre-de-pantallas\/","title":{"rendered":"\u00abConvivencia Escolar te invita a unas vacaciones libre de pantallas\u00bb"},"content":{"rendered":"<p>DEPTO DE CONVIVENCIA ESCOLAR Y LAS VACACIONES<\/p>\n<p>Estamos a pocos d\u00edas de iniciar un per\u00edodo de descanso despu\u00e9s de haber iniciado en marzo de 2023 un proceso de aprendizaje tanto en lo acad\u00e9mico como en el crecimiento que cada uno de nosotros obtenemos como resultado de relacionarnos con los dem\u00e1s y en el cual se deben ir consolidando entre tantos, los valores del respeto y la aceptaci\u00f3n del otro, visto \u00e9ste, como un ser diferente con virtudes y defectos.<\/p>\n<p>Pues bien, en esta \u00e9poca de vacaciones, te incentivamos a que realices un tan necesario proceso de reflexi\u00f3n con el objeto de analizar los aciertos y errores cometidos en este a\u00f1o acad\u00e9mico. As\u00ed tambi\u00e9n, te invitamos a contraer un compromiso personal, para seguir consolidando aquellos aspectos positivos alcanzados este a\u00f1o 2023 y modificar los que entorpecieron tu desarrollo acad\u00e9mico y crecimiento personal.<\/p>\n<p>Finalmente te invitamos a vivir unas vacaciones distintas: disfruta del aire libre, la naturaleza, comparte con tu familia y amigos de manera presencial. Es por lo anterior que compartimos contigo algunas ideas para mantenernos alejados del uso de pantallas y medios tecnol\u00f3gicos y disfrutar a plenitud con las personas que m\u00e1s quieres.<\/p>\n<p>Felices vacaciones, te lo desea Depto de Convivencia Escolar<\/p>\n<div class=\"wp-block-pdfemb-pdf-embedder-viewer\"><a href=\"https:\/\/colegiodelapurisima.cl\/colegio-pc\/wp-content\/uploads\/2023\/12\/AFICHE-PARA-VACACIONES.pdf\" class=\"pdfemb-viewer\" style=\"\" data-width=\"max\" data-height=\"max\" data-toolbar=\"both\" data-toolbar-fixed=\"on\">AFICHE PARA VACACIONES<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>DEPTO DE CONVIVENCIA ESCOLAR Y LAS VACACIONES Estamos a pocos d\u00edas de iniciar un per\u00edodo de descanso despu\u00e9s de haber iniciado en marzo de 2023  [&#8230;]<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-14952","post","type-post","status-publish","format-standard","hentry","category-convivencia-escolar"],"_links":{"self":[{"href":"https:\/\/colegiodelapurisima.cl\/colegio-pc\/wp-json\/wp\/v2\/posts\/14952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/colegiodelapurisima.cl\/colegio-pc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/colegiodelapurisima.cl\/colegio-pc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/colegiodelapurisima.cl\/colegio-pc\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/colegiodelapurisima.cl\/colegio-pc\/wp-json\/wp\/v2\/comments?post=14952"}],"version-history":[{"count":1,"href":"https:\/\/colegiodelapurisima.cl\/colegio-pc\/wp-json\/wp\/v2\/posts\/14952\/revisions"}],"predecessor-version":[{"id":14954,"href":"https:\/\/colegiodelapurisima.cl\/colegio-pc\/wp-json\/wp\/v2\/posts\/14952\/revisions\/14954"}],"wp:attachment":[{"href":"https:\/\/colegiodelapurisima.cl\/colegio-pc\/wp-json\/wp\/v2\/media?parent=14952"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/colegiodelapurisima.cl\/colegio-pc\/wp-json\/wp\/v2\/categories?post=14952"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/colegiodelapurisima.cl\/colegio-pc\/wp-json\/wp\/v2\/tags?post=14952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}